{"id":584,"count":15,"description":"","link":"https:\/\/forbabyboss.com\/nl\/merk\/junama\/","name":"Junama","slug":"junama","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Junama Archives - For Baby Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forbabyboss.com\/nl\/merk-2\/junama\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Junama Archives - For Baby Boss\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forbabyboss.com\/nl\/merk-2\/junama\/\" \/>\n<meta property=\"og:site_name\" content=\"For Baby Boss\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forbabyboss.com\/wp-content\/uploads\/2026\/02\/zestaw2el-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/forbabyboss.com\\\/brand\\\/junama\\\/\",\"url\":\"https:\\\/\\\/forbabyboss.com\\\/brand\\\/junama\\\/\",\"name\":\"Junama Archives - For Baby Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forbabyboss.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forbabyboss.com\\\/brand\\\/junama\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forbabyboss.com\\\/brand\\\/junama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forbabyboss.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Junama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forbabyboss.com\\\/#website\",\"url\":\"https:\\\/\\\/forbabyboss.com\\\/\",\"name\":\"For Baby Boss\",\"description\":\"Shop premium 3-in-1 prams, travel systems and pushchairs at For Baby Boss. Stylish, safe and practical baby travel solutions with fast delivery and excellent value.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forbabyboss.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Junama Archives - For Baby Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forbabyboss.com\/nl\/merk-2\/junama\/","og_locale":"nl_NL","og_type":"article","og_title":"Junama Archives - For Baby Boss","og_url":"https:\/\/forbabyboss.com\/nl\/merk-2\/junama\/","og_site_name":"For Baby Boss","og_image":[{"width":2560,"height":2560,"url":"https:\/\/forbabyboss.com\/wp-content\/uploads\/2026\/02\/zestaw2el-3-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/forbabyboss.com\/brand\/junama\/","url":"https:\/\/forbabyboss.com\/brand\/junama\/","name":"Junama Archives - For Baby Boss","isPartOf":{"@id":"https:\/\/forbabyboss.com\/#website"},"breadcrumb":{"@id":"https:\/\/forbabyboss.com\/brand\/junama\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/forbabyboss.com\/brand\/junama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forbabyboss.com\/"},{"@type":"ListItem","position":2,"name":"Junama"}]},{"@type":"WebSite","@id":"https:\/\/forbabyboss.com\/#website","url":"https:\/\/forbabyboss.com\/","name":"Voor de babybaas","description":"Ontdek de beste 3-in-1 kinderwagens, reissystemen en buggy's bij For Baby Boss. Stijlvolle, veilige en praktische reisoplossingen voor baby's met snelle levering en een uitstekende prijs-kwaliteitverhouding.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forbabyboss.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/forbabyboss.com\/nl\/wp-json\/wp\/v2\/product_brand\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forbabyboss.com\/nl\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/forbabyboss.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/forbabyboss.com\/nl\/wp-json\/wp\/v2\/product?product_brand=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}